{"id":508,"date":"2018-06-11T08:00:14","date_gmt":"2018-06-11T06:00:14","guid":{"rendered":"https:\/\/video-marketing-by.schwarzer.de\/blog\/?p=508"},"modified":"2020-09-21T13:49:04","modified_gmt":"2020-09-21T11:49:04","slug":"die-5-must-haves-fuer-ein-virales-video","status":"publish","type":"post","link":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/","title":{"rendered":"Die 5 Must-haves f\u00fcr ein virales Video"},"content":{"rendered":"<p><!-- <ezTOC> -->Ein virales Video w\u00fcnscht sich fast jeder, der Videos produziert. Gibt es denn etwas cooleres, als dass sich das Video ganz von allein im Netz verbreitet?<br \/>\n<!--more--><\/p>\n<h2>Im Internet verbreiten sich gute Videos h\u00e4ufig viral<\/h2>\n<p>Videos transportieren Inhalte und Werbebotschaften auf visuellem Wege. Betrachtet man die Verschiedenheit der vielen viralen Videos, erscheint es nahezu unm\u00f6glich, genau vorherzusagen, wann ein Video viral geht und wann nicht.<\/p>\n<p>Viele haben sich daran versucht und sind gescheitert, obwohl sie alles genauso gemacht haben wie beim letzten viralen Video \u00e4hnlicher Machart. Und das ist f\u00fcr das Videomarketing ein gro\u00dfes Problem: W\u00e4hrend man andere Kampagnen mehr oder weniger zielgruppenorientiert genau planen kann, h\u00e4ngt beim Thema virales Video viel vom Zufall ab.<\/p>\n<p><strong>Die gute Nachricht:<\/strong><br \/>\n<strong> Es h\u00e4ngt weit weniger vom Zufall ab als es zun\u00e4chst den Anschein hat.<\/strong><\/p>\n<p>Ganz ohne Gl\u00fcck geht es nie \u2013 aber man kann die Chancen daf\u00fcr erh\u00f6hen, dass es funktioniert. Trotzdem: Selbst die besten Marketingstrategen und Werbeagenturen werden unabh\u00e4ngig vom Budget nie eine Garantie daf\u00fcr geben, dass ein Video wirklich viral geht. Doch was ben\u00f6tigt man generell, um eine Chance auf virale Verbreitung zu haben?<\/p>\n<h2>Warum eigentlich viral?<\/h2>\n<p>Der Begriff virale Verbreitung lehnt sich an die Ausbreitung von Krankheiten an, die manchmal schlagartig vom einen Tag auf den anderen explodieren k\u00f6nnen.<\/p>\n<p>Nehmen wir die <strong>Grippewelle<\/strong>: Solange der Virus nur in einer begrenzten Community sein Unwesen treibt, steckt man die Au\u00dfenwelt nicht an. Verl\u00e4sst jemand die Quarant\u00e4ne und f\u00e4hrt etwa mit dem Bus, steckt er potenziell alle Mitreisenden an. Nicht alle davon werden erkranken, viele davon dienen nur als Zwischenwirt. Aber schon der n\u00e4chste, der mit dem Virus nach Hause kommt, steckt mit einiger Wahrscheinlichkeit Frau und Kinder an, die es dann am n\u00e4chsten Tag in der Schule weiter verbreiten. Wir kennen das Prinzip aus allen Katastrophenfilmen, bei denen ein Virus die Hauptrolle spielt.<\/p>\n<p>Bei <strong>viralen Videos<\/strong> (bzw. dem viralen Marketing insgesamt) funktioniert es nach \u00e4hnlichen Prinzipien. Fr\u00fcher war es sehr schwer, ein Video im Internet in der ganzen Welt bekannt zu machen. Es einfach auf die Webseite zu stellen, brachte nicht viel, sofern man nicht sehr viele Zugriffe hatte. Das Verschicken des Videos (bzw. eines Links dazu) per E-Mail konnte funktionieren. Je nachdem, wie viele Kontakte man anschrieb, hatte man das Potenzial, dass diese das Video so toll fanden, dass sie es jeweils mit ihrem gesamten Adressbuch teilten. Genau aus diesem Grund sind W\u00fcrmer, also Schadprogramme, die das Adressbuch eines E-Mail-Kontakts auslesen und weitergeben, so beliebt.<\/p>\n<p>Nat\u00fcrlich kann man auch \u00fcber blindes Spamming Videos per E-Mail verschicken. Aber die Chance, dass jemand eine Mail von einem unbekannten Absender \u00f6ffnet, ist gering.<\/p>\n<h2>Soziale Netzwerke<\/h2>\n<p>Die <strong>Sozialen Netzwerke<\/strong> wie Facebook, Twitter, Instagram oder YouTube haben das alles sehr viel einfacher gemacht:<\/p>\n<ul>\n<li>Ich muss keine Mails mehr verschicken: Poste ich etwas in meiner Timeline, wird es von meinen Followern und Kontakten automatisch auch gesehen.<\/li>\n<li>Mehr noch: Teile ich etwas und geben die Leute viel auf meine Meinung, halten sie es f\u00fcr ein Qualit\u00e4tsmerkmal, wenn ich einen Inhalt teile.<\/li>\n<li>Oft teilen sie ungepr\u00fcft alles weiter und verbreiten Inhalte somit in Windeseile.<\/li>\n<li>Hier kommt das Beispiel mit dem Virus wieder ins Spiel: Jeder meiner Kontakte hat eigene Kontakte, die wiederum andere Menschen in der Kontaktliste haben.<\/li>\n<li>Selbst, wenn sich ein Teil der Kontakte mit den anderen \u00fcberschneidet, kann man durch das Teilen eines Inhalts \u00fcber wenige Ebenen hinweg bereits Zehntausende von Menschen erreichen, die man \u00fcberhaupt nicht kennt.<\/li>\n<\/ul>\n<p><em>Klar, dass dies sowohl f\u00fcr die Verbreitung von Werbung als auch zum Streuen von Fakenews und \u00e4hnlichen Inhalten die perfekte Methode ist.<\/em><\/p>\n<figure id=\"attachment_518\" aria-describedby=\"caption-attachment-518\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-Video-goes-viral-internet-oder-videonet-das-ist-hier-die-frage-01.jpg\"><img class=\"size-full wp-image-518\" src=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-Video-goes-viral-internet-oder-videonet-das-ist-hier-die-frage-01.jpg\" alt=\"Bei viralen Videos (bzw. dem viralen Marketing insgesamt) funktioniert es nach \u00e4hnlichen Prinzipien. Fr\u00fcher war es sehr schwer, ein Video im Internet in der ganzen Welt bekannt zu machen. \" width=\"800\" height=\"613\" srcset=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-Video-goes-viral-internet-oder-videonet-das-ist-hier-die-frage-01.jpg 800w, https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-Video-goes-viral-internet-oder-videonet-das-ist-hier-die-frage-01-300x230.jpg 300w, https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-Video-goes-viral-internet-oder-videonet-das-ist-hier-die-frage-01-600x460.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-518\" class=\"wp-caption-text\">Bei viralen Videos (bzw. dem viralen Marketing insgesamt) funktioniert es nach \u00e4hnlichen Prinzipien. Fr\u00fcher war es sehr schwer, ein Video im Internet in der ganzen Welt bekannt zu machen.<\/figcaption><\/figure>\n<h2>In der Praxis ist es meist schwerer<\/h2>\n<p>Doch wie bringen wir die Menschen dazu, etwas viral zu teilen? In der Theorie ist das obige Beispiel einfach \u2013 in der Praxis haben Sie bestimmt auch schon bemerkt, dass die Follower in der eigenen Timeline l\u00e4ngst nicht alles toll finden, was Sie teilen.<\/p>\n<p>Es m\u00fcssen also <strong>besondere Inhalte<\/strong> sein, die viral gehen k\u00f6nnen. Sie m\u00fcssen jeden ansprechen und einen bestimmten Drang ausl\u00f6sen, alle anderen an genau diesem Inhalt teilhaben zu lassen.<\/p>\n<p><strong>\u201eDas musst du gesehen haben!\u201c,<\/strong><br \/>\n<strong> ist genau das, was wir bei einem viralen Video h\u00f6ren wollen.<\/strong><\/p>\n<p>Wie bereits erw\u00e4hnt, l\u00e4sst sich ein solcher Erfolg nur bedingt planen. Aber wir k\u00f6nnen einige Dinge festlegen, die auf jeden Fall dabei helfen, solchen Content zu produzieren.<\/p>\n<p><strong>Wichtig dabei:<\/strong> Virale Videos sollen gar nicht eine bestimmte Werbeaussage f\u00fcr ein spezifisches Produkt beinhalten.<\/p>\n<p>Das ist im Einzelfall m\u00f6glich und sinnvoll, aber f\u00fcr die Nutzer sind andere Dinge entscheidend:<\/p>\n<ul>\n<li>Das kann ein zu Herzen gehender Inhalt sein,<\/li>\n<li>ein sehr lustiger,<\/li>\n<li>niedlicher oder<\/li>\n<li>trauriger ebenso<\/li>\n<li>wie eine sehr kontroverse Aussage.<\/li>\n<\/ul>\n<p><strong>Geschmackliche Grenzen<\/strong> k\u00f6nnen durchaus ausgetestet werden, denn auch die kontroversen Diskussionen tragen zur viralen Verbreitung bei. Allerdings darf man dabei nie das eigentliche Ziel aus den Augen verlieren.<\/p>\n<p>Ein Beispiel: W\u00fcrde ein Fried-Chicken-Restaurant Bilder von gequ\u00e4lten H\u00fchnern im Video zeigen, w\u00fcrde dies relativ schnell viral gehen. Es k\u00f6nnte aber dazu f\u00fchren, dass viele Menschen nicht mehr in diese Restaurants gehen.<\/p>\n<p><strong>Provozieren, nur um zu provozieren, kann also auch nach hinten losgehen.<\/strong><\/p>\n<figure id=\"attachment_526\" aria-describedby=\"caption-attachment-526\" style=\"width: 796px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video-das-gilt-es-zu-beachten.jpg\"><img class=\"size-full wp-image-526\" src=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video-das-gilt-es-zu-beachten.jpg\" alt=\"Virale Videos sollen gar nicht eine bestimmte Werbeaussage f\u00fcr ein spezifisches Produkt beinhalten. (#01)\" width=\"796\" height=\"567\" srcset=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video-das-gilt-es-zu-beachten.jpg 796w, https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video-das-gilt-es-zu-beachten-300x214.jpg 300w, https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video-das-gilt-es-zu-beachten-269x192.jpg 269w\" sizes=\"(max-width: 796px) 100vw, 796px\" \/><\/a><figcaption id=\"caption-attachment-526\" class=\"wp-caption-text\">Virale Videos sollen gar nicht eine bestimmte Werbeaussage f\u00fcr ein spezifisches Produkt beinhalten. (#01)<\/figcaption><\/figure>\n<h2>Das brauchen wir f\u00fcr ein virales Video:<\/h2>\n<p><strong>1. Eine gute Idee<\/strong><\/p>\n<p>Es scheint m\u00fc\u00dfig, das \u00fcberhaupt zu erw\u00e4hnen, aber selbst solcher Content, der eigentlich total zuf\u00e4llig oder beliebig aussieht, hat oft eine gute Idee zum Hintergrund. Man w\u00fcrde kaum glauben, wie viele virale Videos im Netz sehr zuf\u00e4llig aufgenommen aussehen, tats\u00e4chlich aber gestellt sind. Wichtig ist, dass die zentrale Idee, die transportiert wird, gut genug ist, um den User in der gew\u00fcnschten Zielgruppe anzusprechen.<\/p>\n<p><strong>2. Die richtige Zielgruppe festlegen<\/strong><\/p>\n<p>Das gilt bei allen Formen der Werbung \u2013 und ist insofern nichts Neues. Aber: Auch virale Videos wenden sich immer an eine bestimme Zielgruppe. Die kann je nach Inhalt sehr weit gefasst sein, aber ganz ohne geht es in den meisten F\u00e4llen nicht. Begreifen muss man au\u00dferdem, dass man nicht viral gehen kann und gleichzeitig Everybody&#8217;s Darling bleiben wird. Denn jetzt kommt Punkt 3:<\/p>\n<p><strong>3. Der Inhalt muss zum Teilen provozieren<\/strong><\/p>\n<p>Das s\u00fc\u00dfe Hundebaby oder ein Katzenvideo gehen aufgrund des Niedlichkeitsfaktors schnell viral. Aber damit l\u00e4sst sich in der Regel keine gro\u00dfe Kampagne aufziehen. Um viral zu werden, bedarf es im Videomarketing fast in allen Branchen und Bereichen auch einer gewissen Kontroverse. Dies gilt umso mehr bei politischen Botschaften oder \u00e4hnlichen Ideen. Deswegen sollte ein virales Video unbedingt auch polarisieren, damit es zur regen Diskussion kommt. Denn: Nur, wer es gesehen hat, wird auch mitdiskutieren k\u00f6nnen \u2013 ergo wird es auch von den Gegnern einer These h\u00e4ufig verbreitet.<\/p>\n<p><strong>4. Diskussionen laufen lassen<\/strong><\/p>\n<p>Die daraus entstehenden Diskussionen k\u00f6nnen sehr heftig werden oder sogar zum Shitstorm ausarten. Das ist nat\u00fcrlich dann nicht mehr so toll. Trotzdem: Bis zu einem gewissen Grad sollten Sie die Diskussionen in den Sozialen Medien (z. B. auf Ihrer Facebookseite) laufen lassen und nicht steuernd eingreifen. Was nicht bedeutet, dass Sie nicht mit den potenziellen Kunden interagieren sollen. Stellen Sie sich der Diskussion, beziehen Sie eine Position \u2013 viral bleibt es dann von selbst.<\/p>\n<p><strong>5. M\u00f6glichst barrierefrei bleiben<\/strong><\/p>\n<p>Ein Video geht nur dann viral, wenn es keinen gro\u00dfen Aufwand f\u00fcr den Nutzer bedeutet, es anzusehen oder zu teilen. Verzichten Sie also auf Webseiten, bei denen man sich erst mit einer E-Mail-Adresse registrieren muss, um ein Video sehen zu k\u00f6nnen. Nutzen Sie statt dessen alle Kan\u00e4le von YouTube \u00fcber Facebook bis Instagram und Co., um ein Video zu verbreiten.<\/p>\n<figure id=\"attachment_522\" aria-describedby=\"caption-attachment-522\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-virales-video-marketing-7-Tipps-so-wird-dein-video-ein-viraler-hit.jpg\"><img class=\"size-full wp-image-522\" src=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-virales-video-marketing-7-Tipps-so-wird-dein-video-ein-viraler-hit.jpg\" alt=\"Wichtig ist, die Mechanismen des viralen Marketings zu verinnerlichen, bevor man \u00fcberhaupt anf\u00e4ngt, etwas zu produzieren. Denn so beliebig und zuf\u00e4llig gute virale Videos am Ende wirken, so durchgeplant sind sie in der Regel.\" width=\"800\" height=\"613\" srcset=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-virales-video-marketing-7-Tipps-so-wird-dein-video-ein-viraler-hit.jpg 800w, https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-virales-video-marketing-7-Tipps-so-wird-dein-video-ein-viraler-hit-300x230.jpg 300w, https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Infografik-virales-video-marketing-7-Tipps-so-wird-dein-video-ein-viraler-hit-600x460.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-522\" class=\"wp-caption-text\">Wichtig ist, die Mechanismen des viralen Marketings zu verinnerlichen, bevor man \u00fcberhaupt anf\u00e4ngt, etwas zu produzieren. Denn so beliebig und zuf\u00e4llig gute virale Videos am Ende wirken, so durchgeplant sind sie in der Regel.<\/figcaption><\/figure>\n<h2>Je barrierefreier, desto besser.<\/h2>\n<p>Wenn Sie nur mit Bildern auskommen, ist es am einfachsten. M\u00fcssen Erkl\u00e4rungen abgegeben werden, sollte die Sprache von m\u00f6glichst vielen in der Zielgruppe gesprochen werden. Untertitel oder Voiceovers sind ebenfalls zu empfehlen (eventuell mehrsprachig), um Geh\u00f6rlose oder Blinde einzubinden und \u00fcber die \u201eAudio-Aus\u201c-Schwelle in den Newsfeeds zu kommen. Denn viele Menschen deaktivieren den Ton standardm\u00e4\u00dfig beim Scrollen durch ihre Timeline. Je einfacher der Zugang, desto wahrscheinlicher die Viralit\u00e4t.<\/p>\n<h2>Fazit: Man kann dem Zufall beim viralen Video auf die Spr\u00fcnge helfen<\/h2>\n<p>Es gibt noch viele weitere Punkte, die sich mit der Planung einer derartigen Kampagne befassen und den verschiedenen M\u00f6glichkeiten, wie man Zielgruppen am besten anspricht. Das w\u00fcrde aber im Rahmen dieses Artikels zu weit f\u00fchren.<\/p>\n<p>Wichtig ist, die <strong>Mechanismen des viralen Marketings<\/strong> zu verinnerlichen, bevor man \u00fcberhaupt anf\u00e4ngt, etwas zu produzieren. Denn so beliebig und zuf\u00e4llig gute virale Videos am Ende wirken, so durchgeplant sind sie in der Regel. Nur selten werden Inhalte tats\u00e4chlich durch reinen Zufall ein viraler Erfolg \u2013 dahinter stehen dann fast immer irgendwelche Privatleute, die gar nicht beabsichtigt hatten, viral zu gehen.<\/p>\n<h2>F\u00fcr das Videomarketing ist das nat\u00fcrlich keine planbare Strategie<\/h2>\n<p>Um ein <strong>virales Video<\/strong> zu produzieren, sollte man also immer ein schl\u00fcssiges Konzept erarbeiten und mit einer Agentur kooperieren, die in der Lage ist, solchen Content hochwertig zu produzieren UND anschlie\u00dfend \u00fcber die entsprechenden Kan\u00e4le zu verbreiten.<\/p>\n<p><em>Gelingt das, ist der geplante Erfolg auch bei viralen Videos durchaus machbar. <\/em><\/p>\n<p>Wenn Sie mehr wissen m\u00f6chten zu den Besonderheiten des viralen Marketings und wie man Videos am besten in Sozialen Netzwerken seeden kann, sollten Sie einen Blick auf unsere anderen Artikel zum Thema werfen:<\/p>\n<p><a href=\"\/blog\/virales-marketing-beispiele\/\" rel=\"noopener noreferrer\" target=\"_blank\">video-marketing-by.schwarzer.de\/virales-marketing-beispiele\/<\/a><br \/>\n&amp;<br \/>\n<a href=\"\/blog\/video-seeding-checkliste\/\" rel=\"noopener noreferrer\" target=\"_blank\">video-marketing-by.schwarzer.de\/video-seeding-checkliste\/<\/a><\/p>\n<hr \/>\n<p>Bildnachweis:\u00a9Shutterstock-Titelbild: T. L. Furrer\u00a0 -#01 Rawpixel.com<\/p>\n<p>Infografiken: Schwarzer.de<!-- <\/ezTOC> --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein virales Video w\u00fcnscht sich fast jeder, der Videos produziert. Gibt es denn etwas cooleres, als dass sich das Video [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"features_image":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video.jpg","rk_cat":null,"rk_date":"11.06.2018","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die 5 Must-haves f\u00fcr ein virales Video - video-marketing-by.schwarzer.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die 5 Must-haves f\u00fcr ein virales Video - video-marketing-by.schwarzer.de\" \/>\n<meta property=\"og:description\" content=\"Ein virales Video w\u00fcnscht sich fast jeder, der Videos produziert. Gibt es denn etwas cooleres, als dass sich das Video [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/\" \/>\n<meta property=\"og:site_name\" content=\"video-marketing-by.schwarzer.de\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-11T06:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-21T11:49:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans-J\u00fcrgen Schwarzer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/#website\",\"url\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/\",\"name\":\"video-marketing-by.schwarzer.de\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#primaryimage\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video.jpg\",\"contentUrl\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video.jpg\",\"width\":700,\"height\":335,\"caption\":\"Die 5 Must-haves f\u00fcr ein virales Video\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#webpage\",\"url\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/\",\"name\":\"Die 5 Must-haves f\u00fcr ein virales Video - video-marketing-by.schwarzer.de\",\"isPartOf\":{\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#primaryimage\"},\"datePublished\":\"2018-06-11T06:00:14+00:00\",\"dateModified\":\"2020-09-21T11:49:04+00:00\",\"author\":{\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/#\/schema\/person\/fc6da8019257c03233a2c180d83bcc71\"},\"breadcrumb\":{\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die 5 Must-haves f\u00fcr ein virales Video\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/#\/schema\/person\/fc6da8019257c03233a2c180d83bcc71\",\"name\":\"Hans-J\u00fcrgen Schwarzer\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/video-marketing-by.schwarzer.de\/blog\/#personlogo\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e9a54aaac87c32742c669aa0d5556c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e9a54aaac87c32742c669aa0d5556c1?s=96&d=mm&r=g\",\"caption\":\"Hans-J\u00fcrgen Schwarzer\"},\"description\":\"Hans-J\u00fcrgen Schwarzer leitet die Digital-Agentur schwarzer.de software + internet gmbh. Als Unternehmer und Verleger in Personalunion wie auch als leidenschaftlicher Blogger geh\u00f6rt er zu den Hauptautoren verschiedener Online-Magazine. Innerhalb seiner breiten Palette an Themen liegen dem Mainzer Lokalpatrioten dabei vermeintlich \u201eschr\u00e4ge\u201c Ideen und technische Novit\u00e4ten besonders am Herzen - Nerdstuff, wie es heute hei\u00dft.\",\"sameAs\":[\"http:\/\/www.schwarzer.de\"],\"url\":\"#\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die 5 Must-haves f\u00fcr ein virales Video - video-marketing-by.schwarzer.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/","og_locale":"de_DE","og_type":"article","og_title":"Die 5 Must-haves f\u00fcr ein virales Video - video-marketing-by.schwarzer.de","og_description":"Ein virales Video w\u00fcnscht sich fast jeder, der Videos produziert. Gibt es denn etwas cooleres, als dass sich das Video [&hellip;]","og_url":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/","og_site_name":"video-marketing-by.schwarzer.de","article_published_time":"2018-06-11T06:00:14+00:00","article_modified_time":"2020-09-21T11:49:04+00:00","og_image":[{"width":700,"height":335,"url":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans-J\u00fcrgen Schwarzer","Gesch\u00e4tzte Lesezeit":"8 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/#website","url":"https:\/\/video-marketing-by.schwarzer.de\/blog\/","name":"video-marketing-by.schwarzer.de","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/video-marketing-by.schwarzer.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"ImageObject","@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#primaryimage","inLanguage":"de-DE","url":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video.jpg","contentUrl":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-content\/uploads\/2018\/06\/Die-5-Must-haves-fuer-ein-virales-Video.jpg","width":700,"height":335,"caption":"Die 5 Must-haves f\u00fcr ein virales Video"},{"@type":"WebPage","@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#webpage","url":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/","name":"Die 5 Must-haves f\u00fcr ein virales Video - video-marketing-by.schwarzer.de","isPartOf":{"@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#primaryimage"},"datePublished":"2018-06-11T06:00:14+00:00","dateModified":"2020-09-21T11:49:04+00:00","author":{"@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/#\/schema\/person\/fc6da8019257c03233a2c180d83bcc71"},"breadcrumb":{"@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/die-5-must-haves-fuer-ein-virales-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/video-marketing-by.schwarzer.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Die 5 Must-haves f\u00fcr ein virales Video"}]},{"@type":"Person","@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/#\/schema\/person\/fc6da8019257c03233a2c180d83bcc71","name":"Hans-J\u00fcrgen Schwarzer","image":{"@type":"ImageObject","@id":"https:\/\/video-marketing-by.schwarzer.de\/blog\/#personlogo","inLanguage":"de-DE","url":"https:\/\/secure.gravatar.com\/avatar\/2e9a54aaac87c32742c669aa0d5556c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e9a54aaac87c32742c669aa0d5556c1?s=96&d=mm&r=g","caption":"Hans-J\u00fcrgen Schwarzer"},"description":"Hans-J\u00fcrgen Schwarzer leitet die Digital-Agentur schwarzer.de software + internet gmbh. Als Unternehmer und Verleger in Personalunion wie auch als leidenschaftlicher Blogger geh\u00f6rt er zu den Hauptautoren verschiedener Online-Magazine. Innerhalb seiner breiten Palette an Themen liegen dem Mainzer Lokalpatrioten dabei vermeintlich \u201eschr\u00e4ge\u201c Ideen und technische Novit\u00e4ten besonders am Herzen - Nerdstuff, wie es heute hei\u00dft.","sameAs":["http:\/\/www.schwarzer.de"],"url":"#"}]}},"_links":{"self":[{"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/posts\/508"}],"collection":[{"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/comments?post=508"}],"version-history":[{"count":18,"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/posts\/508\/revisions"}],"predecessor-version":[{"id":1212,"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/posts\/508\/revisions\/1212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/media\/525"}],"wp:attachment":[{"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/media?parent=508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/categories?post=508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/video-marketing-by.schwarzer.de\/blog\/wp-json\/wp\/v2\/tags?post=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}